{"id":100301,"date":"2026-04-16T10:24:59","date_gmt":"2026-04-16T10:24:59","guid":{"rendered":"https:\/\/xtreme4x4.pl\/produkt\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/"},"modified":"2026-04-16T11:12:33","modified_gmt":"2026-04-16T11:12:33","slug":"torba-na-zestaw-do-wyciagania-large-factor-55-2","status":"publish","type":"product","link":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/","title":{"rendered":"Large Factor 55 Pulling Kit Bag"},"content":{"rendered":"<ul>\n<li>Durable YKK zippers<\/li>\n<li>Waterproof case<\/li>\n<li>Orange interior<\/li>\n<li>Powder-coated steel shoulder strap rings<\/li>\n<li>The rectangular shape allows for convenient arrangement of equipment<\/li>\n<li>Made in the USA<\/li>\n<\/ul>\n<p><strong>Dimensions:<\/strong><\/p>\n<ul>\n<li>Length 21\u2033<\/li>\n<li>Height 14\u2033<\/li>\n<li>Width approx. 12\u2033<\/li>\n<\/ul>\n<p><strong>Comments:<\/strong><\/p>\n<ul>\n<li>Do not use detergents, solvents or other harsh cleaning agents<\/li>\n<li>Do not wash in the washing machine<\/li>\n<li>Do not dry clean<\/li>\n<li>Does not include a shoulder strap<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Wytrzyma\u0142e zamki b\u0142yskawiczne YKK Wodoodporna kadura Wn\u0119trze w kolorze pomara\u0144czowym Stalowe, malowane proszkowo pier\u015bcienie do paska na rami\u0119 Prostok\u0105tny kszta\u0142t pozwala na wygodne rozmieszczenie sprz\u0119tu Wykonane z USA Wymiary: D\u0142ugo\u015b\u0107 21\u2033 Wysoko\u015b\u0107 14\u2033 Szeroko\u015b\u0107 ok. 12\u2033 Uwagi: Nie u\u017cywa\u0107 detergent\u00f3w, rozpuszczalnik\u00f3w ani innych ostrych \u015brodk\u00f3w czyszcz\u0105cych Nie pra\u0107 w pralce Nie czy\u015bci\u0107 chemicznie Nie zawiera<\/p>\n<div class=\"klb-readmore button\"><a class=\"btn link\" href=\"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/\">Read More <i class=\"klbth-icon-right-arrow\"><\/i><\/a><\/div>","protected":false},"featured_media":36531,"template":"","meta":[],"product_brand":[],"product_cat":[539,191,619,545,6350],"product_tag":[],"class_list":["post-100301","product","type-product","status-publish","has-post-thumbnail","product_cat-factor-55","product_cat-przechowywanie","product_cat-torby-i-plecaki","product_cat-zestawy-do-wyciagania","product_cat-zestawy-do-wyciagania-outdoor-90","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torba na zestaw do wyci\u0105gania large Factor 55 - Sklep Xtreme 4x4<\/title>\n<meta name=\"description\" content=\"Torba na zestaw do wyci\u0105gania large Factor 55 do kupienia w naszym sklepie. Sprawd\u017a!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torba na zestaw do wyci\u0105gania large Factor 55 - Sklep Xtreme 4x4\" \/>\n<meta property=\"og:description\" content=\"Torba na zestaw do wyci\u0105gania large Factor 55 do kupienia w naszym sklepie. Sprawd\u017a!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Xtreme 4x4\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T11:12:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xtreme4x4.pl\/wp-content\/uploads\/2026\/03\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/\",\"url\":\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/\",\"name\":\"Torba na zestaw do wyci\u0105gania large Factor 55 - Sklep Xtreme 4x4\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xtreme4x4.pl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg\",\"datePublished\":\"2026-04-16T10:24:59+00:00\",\"dateModified\":\"2026-04-16T11:12:33+00:00\",\"description\":\"Torba na zestaw do wyci\u0105gania large Factor 55 do kupienia w naszym sklepie. Sprawd\u017a!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xtreme4x4.pl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg\",\"contentUrl\":\"https:\\\/\\\/xtreme4x4.pl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/en\\\/product\\\/torba-na-zestaw-do-wyciagania-large-factor-55-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/xtreme4x4.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sklep\",\"item\":\"https:\\\/\\\/xtreme4x4.pl\\\/sklep\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Torba na zestaw do wyci\u0105gania large Factor 55\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xtreme4x4.pl\\\/#website\",\"url\":\"https:\\\/\\\/xtreme4x4.pl\\\/\",\"name\":\"Xtreme 4x4\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xtreme4x4.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torba na zestaw do wyci\u0105gania large Factor 55 - Sklep Xtreme 4x4","description":"Torba na zestaw do wyci\u0105gania large Factor 55 do kupienia w naszym sklepie. Sprawd\u017a!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/","og_locale":"en_GB","og_type":"article","og_title":"Torba na zestaw do wyci\u0105gania large Factor 55 - Sklep Xtreme 4x4","og_description":"Torba na zestaw do wyci\u0105gania large Factor 55 do kupienia w naszym sklepie. Sprawd\u017a!","og_url":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/","og_site_name":"Xtreme 4x4","article_modified_time":"2026-04-16T11:12:33+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/xtreme4x4.pl\/wp-content\/uploads\/2026\/03\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/","url":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/","name":"Torba na zestaw do wyci\u0105gania large Factor 55 - Sklep Xtreme 4x4","isPartOf":{"@id":"https:\/\/xtreme4x4.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/#primaryimage"},"image":{"@id":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/#primaryimage"},"thumbnailUrl":"https:\/\/xtreme4x4.pl\/wp-content\/uploads\/2026\/03\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg","datePublished":"2026-04-16T10:24:59+00:00","dateModified":"2026-04-16T11:12:33+00:00","description":"Torba na zestaw do wyci\u0105gania large Factor 55 do kupienia w naszym sklepie. Sprawd\u017a!","breadcrumb":{"@id":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/#primaryimage","url":"https:\/\/xtreme4x4.pl\/wp-content\/uploads\/2026\/03\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg","contentUrl":"https:\/\/xtreme4x4.pl\/wp-content\/uploads\/2026\/03\/torba-na-zestaw-do-wyciagania-large-factor-55.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/xtreme4x4.pl\/en\/product\/torba-na-zestaw-do-wyciagania-large-factor-55-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/xtreme4x4.pl\/"},{"@type":"ListItem","position":2,"name":"Sklep","item":"https:\/\/xtreme4x4.pl\/sklep\/"},{"@type":"ListItem","position":3,"name":"Torba na zestaw do wyci\u0105gania large Factor 55"}]},{"@type":"WebSite","@id":"https:\/\/xtreme4x4.pl\/#website","url":"https:\/\/xtreme4x4.pl\/","name":"Xtreme 4x4","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xtreme4x4.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/product\/100301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/media\/36531"}],"wp:attachment":[{"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/media?parent=100301"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/product_brand?post=100301"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/product_cat?post=100301"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xtreme4x4.pl\/en\/wp-json\/wp\/v2\/product_tag?post=100301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}